{"id":12303,"date":"2024-09-09T12:11:06","date_gmt":"2024-09-09T15:11:06","guid":{"rendered":"https:\/\/www.correiodascidades.com.br\/v1\/?p=12303"},"modified":"2024-09-09T12:11:30","modified_gmt":"2024-09-09T15:11:30","slug":"12303","status":"publish","type":"post","link":"https:\/\/www.correiodascidades.com.br\/v1\/2024\/09\/09\/12303\/","title":{"rendered":"Governo divulga 1.624 vagas tempor\u00e1rias para educadores na Bahia"},"content":{"rendered":"<div class=\"post-outer\">\n<div class=\"post hentry\">\n<h3 class=\"post-title entry-title\"><\/h3>\n<div id=\"post-body-3142541125390219003\" class=\"post-body entry-content\">\n<div class=\"separator\"><a href=\"https:\/\/blogger.googleusercontent.com\/img\/a\/AVvXsEiJp2jJ6tTBmu5dZqVis0YWdqZ4EF_zWTi34TFYuyoqBA0UvkxFOtHJRtGTU-PWhs6Oxmrq6YZ_7_P_xGXcyC3LMbe2t4zdz-qDomPTtZyU4mmGGrh-C1OzK419V_BNvDjd0KJ19-ZZ-q5I0WokImg5nR2t9B1tFwnLABWqEPaJfsFOLr5sAjP-dvojh78\"><img loading=\"lazy\" src=\"https:\/\/blogger.googleusercontent.com\/img\/a\/AVvXsEiJp2jJ6tTBmu5dZqVis0YWdqZ4EF_zWTi34TFYuyoqBA0UvkxFOtHJRtGTU-PWhs6Oxmrq6YZ_7_P_xGXcyC3LMbe2t4zdz-qDomPTtZyU4mmGGrh-C1OzK419V_BNvDjd0KJ19-ZZ-q5I0WokImg5nR2t9B1tFwnLABWqEPaJfsFOLr5sAjP-dvojh78=w516-h343\" alt=\"\" width=\"516\" height=\"343\" data-original-height=\"493\" data-original-width=\"740\" \/><\/a><\/div>\n<p>&nbsp;<\/p>\n<p>O Governo do Estado abriu um processo seletivo para contrata\u00e7\u00e3o de 1.624 profissionais da educa\u00e7\u00e3o em diversas cidades da Bahia. As oportunidades foram divulgadas no Di\u00e1rio Oficial de sexta-feira (7) e as inscri\u00e7\u00f5es poder\u00e3o ser feitas a partir de 12 de setembro.<\/p>\n<p>As inscri\u00e7\u00f5es dever\u00e3o ser feitas pela internet, at\u00e9 2 de outubro. As oportunidades s\u00e3o para diversas cidades da Bahia, como Salvador, Feira de Santana, Itabuna, Ilh\u00e9us, Serrinha, Teixeira de Freitas e Guanambi.<\/p>\n<p>Todas as contrata\u00e7\u00f5es s\u00e3o em Regime Especial de Direito Administrativo (Reda) e os profissionais trabalhar\u00e3o entre 20h e 30h semanais. O prazo do contrato \u00e9 de 36 meses e pode ser prorrogado por igual per\u00edodo.<\/p>\n<div id=\"chunk-24uga\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-id=\"7\" data-block-type=\"unstyled\" data-block-weight=\"7\">\n<p class=\" content-text__container \" data-mrf-recirculation=\"Article links\" data-track-category=\"Link no Texto\" data-track-links=\"\">Confira os profissionais que podem se inscrever:<\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-cuf6m\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-id=\"8\" data-block-type=\"unstyled\" data-block-weight=\"8\">\n<div>Cuidador educacional<\/div>\n<div>Quantidade de vagas: 509<\/div>\n<div>Carga hor\u00e1ria: 30h Int\u00e9rprete de libras<\/div>\n<\/div>\n<\/div>\n<div id=\"chunk-cfmfo\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-id=\"9\" data-block-type=\"unstyled\" data-block-weight=\"10\">\n<div>Quantidade de vagas: 173<\/div>\n<div>Carga hor\u00e1ria: 20k Instrutor de libras<\/div>\n<\/div>\n<\/div>\n<div id=\"chunk-abloj\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-id=\"10\" data-block-type=\"unstyled\" data-block-weight=\"8\">\n<div>Quantidade de vagas: 78<\/div>\n<div>Carga hor\u00e1ria: Brailista<\/div>\n<\/div>\n<\/div>\n<div id=\"chunk-17gn9\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-id=\"11\" data-block-type=\"unstyled\" data-block-weight=\"6\">\n<div>Quantidade de vagas: 101<\/div>\n<div>Carga hor\u00e1ria: 20h T\u00e9cnico de atendimento educacional especializado \u2013 AEE<\/div>\n<\/div>\n<\/div>\n<div id=\"chunk-afrpq\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-id=\"12\" data-block-type=\"unstyled\" data-block-weight=\"14\">\n<div>Quantidade de vagas: 763<\/div>\n<div>Carga hor\u00e1ria: 20h<\/div>\n<p>As provas ser\u00e3o realizadas no dia 17 de novembro deste ano, nas seguintes cidades: Alagoinhas, Amargosa, Barreiras, Bom jesus da Lapa, Caetit\u00e9, Eun\u00e1polis, Feira de Santana, Ipir\u00e1, Irec\u00ea, Itaberaba, Itabuna, Itapetinga, Jacobina, Jequi\u00e9, Juazeiro, Maca\u00fabas, Paulo Afonso, Ribeira do Pombal, Santa maria da Vit\u00f3ria, Santo Ant\u00f4nio de Jesus, Seabra, Senhor do Bonfim, Serrinha, Teixeira de Freitas, Valen\u00e7a e Vit\u00f3ria da Conquista.<\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-d32cj\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-id=\"14\" data-block-type=\"unstyled\" data-block-weight=\"14\">\n<p class=\" content-text__container \" data-mrf-recirculation=\"Article links\" data-track-category=\"Link no Texto\" data-track-links=\"\">A data prevista para homologa\u00e7\u00e3o do processo \u00e9 em 17 de janeiro de 2025.<\/p>\n<\/div>\n<\/div>\n<div><a href=\"https:\/\/www.verdinhoitabuna.blog.br\/2024\/09\/nova-etapa-do-pix-vai-permitir.html\">Nova etapa do Pix vai permitir pagamento por aproxima\u00e7\u00e3o; entenda como funciona<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"post-outer\">\n<div class=\"post hentry\">\n<div class=\"post-header\">\n<div class=\"post-header-line-1\"><\/div>\n<\/div>\n<div id=\"post-body-7493776189872411324\" class=\"post-body entry-content\">\n<div class=\"separator\"><a href=\"https:\/\/blogger.googleusercontent.com\/img\/a\/AVvXsEhbFsi-pofrs2H711JIM0m7Bg7yIXnr-O0Id34W4sIgHrsL3k0C4Ma0qEMaClAnOd0U_T2A_LofJDYZ21MYz_-5LtExfKv_BHFn6C9oLLVloyrT_G07ezp6ozgTB8bxSMjhh6tJlXj8DNfp0hV2iXuvvadwxCTSstrCx7QO6EhXdSUa6MAlgYt1pXJDFWY\"><img loading=\"lazy\" src=\"https:\/\/blogger.googleusercontent.com\/img\/a\/AVvXsEhbFsi-pofrs2H711JIM0m7Bg7yIXnr-O0Id34W4sIgHrsL3k0C4Ma0qEMaClAnOd0U_T2A_LofJDYZ21MYz_-5LtExfKv_BHFn6C9oLLVloyrT_G07ezp6ozgTB8bxSMjhh6tJlXj8DNfp0hV2iXuvvadwxCTSstrCx7QO6EhXdSUa6MAlgYt1pXJDFWY=w557-h313\" alt=\"\" width=\"557\" height=\"313\" data-original-height=\"1080\" data-original-width=\"1920\" \/><\/a><\/div>\n<p>&nbsp;<\/p>\n<p>O Pix por aproxima\u00e7\u00e3o est\u00e1 previsto para fevereiro de 2025. A partir dessa data, todas as institui\u00e7\u00f5es financeiras credenciadas ao BC dever\u00e3o oferecer o servi\u00e7o por meio das iniciadores de pagamento credenciadas.<\/p>\n<p>Segundo o regulador, as pessoas s\u00f3 v\u00e3o precisar cadastrar uma chave Pix em uma carteira digital habilitada \u2013como Google Pay ou PicPay\u2013, que permita fazer o pagamentos pelo celular ou rel\u00f3gio digital. A partir desse momento, ser\u00e1 poss\u00edvel pagar em lojas f\u00edsicas com o Pix por aproxima\u00e7\u00e3o como se faz hoje com o cart\u00e3o.<\/p>\n<p>&#8220;\u00c9 importante que a disponibilidade dessa nova forma de utiliza\u00e7\u00e3o do Pix se d\u00ea por meio da abertura do mercado \u00e0 participa\u00e7\u00e3o de diferentes players, estimulando a competi\u00e7\u00e3o e ampliando o acesso das pessoas \u00e0 funcionalidade&#8221;, diz Fernanda Garibaldi, diretora-executiva da Zetta, uma entidade fundada pelo Nubank e pelo Google para tratar de pagamentos online.<\/p>\n<p>A entidade pleiteia que essa abertura deve estar prevista na regula\u00e7\u00e3o para que os impactos positivos esperados sejam de fato atingidos.<\/p>\n<p>&#8220;Para manter a competitividade do setor, enxergamos como necess\u00e1ria a discuss\u00e3o quanto a operacionaliza\u00e7\u00e3o para que institui\u00e7\u00e3o participante do ecossistema possa realizar a transa\u00e7\u00e3o, sem que seja preciso passar por wallets espec\u00edficas e sem que sejam cobrados custos que impe\u00e7am que players menores acessem a tecnologia, trazendo mais autonomia e fomentando a inova\u00e7\u00e3o para aprimoramento da experi\u00eancia dos usu\u00e1rios&#8221;, afirma Garibaldi.<\/p>\n<p>Caso a Apple n\u00e3o abra seu sistema a carteiras digitais at\u00e9 fevereiro, a empresa pode estar sujeita a um processo no Cade (Conselho Administrativo de Defesa Econ\u00f4mica).<\/p>\n<p>O principal argumento da Apple para manter seu sistema de pagamento por aproxima\u00e7\u00e3o fechado \u00e9 a preven\u00e7\u00e3o de fraudes. \u00c9 um padr\u00e3o de seguran\u00e7a por obscuridade, quando uma empresa n\u00e3o divulga informa\u00e7\u00f5es t\u00e9cnicas de uma ferramenta, para deixar criminosos tamb\u00e9m no escuro.<\/p>\n<p><b>O PIX POR APROXIMA\u00c7\u00c3O \u00c9 SEGURO?<\/b><\/p>\n<p>De acordo com Wagner Martin, da Veritran, os protocolos do Pix por aproxima\u00e7\u00e3o determinados pelo Banco Central devem garantir seguran\u00e7a para o cliente. Al\u00e9m da criptografia tradicional do NFC, o cliente ter\u00e1 de confirmar o pagamento com uma senha, token ou chave biom\u00e9trica (digital ou reconhecimento facial).<\/p>\n<p>&#8220;\u00c9 um sistema baseado na tecnologia do iniciador de pagamentos que j\u00e1 est\u00e1 em uso pelo menos desde o ano passado e demonstrando integridade&#8221;, diz Martin.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"post-outer\">\n<div class=\"post hentry\">\n<h3 class=\"post-title entry-title\"><a href=\"https:\/\/www.verdinhoitabuna.blog.br\/2024\/09\/opiniao-uso-de-lula-como-bengala.html\">Opini\u00e3o: Uso de Lula como bengala desgasta presidente e retroalimenta falta de renova\u00e7\u00e3o pol\u00edtica<\/a><\/h3>\n<div class=\"post-header\">\n<div class=\"post-header-line-1\"><\/div>\n<\/div>\n<div id=\"post-body-5765559710670222544\" class=\"post-body entry-content\">\n<div class=\"separator\"><a href=\"https:\/\/blogger.googleusercontent.com\/img\/a\/AVvXsEj23BKQLsnWLeSqJgA7qJg0kiE6Qw3YsNHiQ3prh69U0CzeM0A-0DYfpzd7v8dIMSUndrf6-zrd2liv5iGg5PtcSHnZAUVFylr9cFTfgTHHmTMjRuVhGcvVOdyqdssrEB9J8uxRy145c5VmBLjYnxzgVMxszkSLORoU_CxeCjpG1JaHSp_ULZUNx6pL7hc\"><img loading=\"lazy\" src=\"https:\/\/blogger.googleusercontent.com\/img\/a\/AVvXsEj23BKQLsnWLeSqJgA7qJg0kiE6Qw3YsNHiQ3prh69U0CzeM0A-0DYfpzd7v8dIMSUndrf6-zrd2liv5iGg5PtcSHnZAUVFylr9cFTfgTHHmTMjRuVhGcvVOdyqdssrEB9J8uxRy145c5VmBLjYnxzgVMxszkSLORoU_CxeCjpG1JaHSp_ULZUNx6pL7hc=w577-h303\" alt=\"\" width=\"577\" height=\"303\" data-original-height=\"402\" data-original-width=\"764\" \/><\/a><\/div>\n<p>&nbsp;<\/p>\n<p>Dez em cada 10 candidaturas ligadas ao PT fazem refer\u00eancia ao \u201ctime de Lula\u201d ou a \u201ccandidato de Lula\u201d. A import\u00e2ncia do presidente Luiz In\u00e1cio Lula da Silva e a relev\u00e2ncia dele enquanto \u201cgrande eleitor\u201d \u00e9 ineg\u00e1vel. No entanto, essa bengala, de t\u00e3o recorrente, acaba banalizando a figura do presidente, ao mesmo tempo em que gera a retroalimenta\u00e7\u00e3o da falta de renova\u00e7\u00e3o na pol\u00edtica que, em tese, o pr\u00f3prio Lula se manifesta contr\u00e1rio. Lula \u00e9 maior que o PT e os partidos aliados, mas n\u00e3o deveria ele ser o \u00fanico mote para impulsionar candidaturas.<\/p>\n<p>Um dos casos mais emblem\u00e1ticos tem sido o esfor\u00e7o de Geraldo Jr. (MDB) em Salvador tentar ser associado todo o tempo a Lula e ao governador Jer\u00f4nimo Rodrigues (PT). O vice-governador mudou de roupa em 2022 e ainda tenta se adequar ao novo vestu\u00e1rio na disputa eleitoral pela prefeitura da capital baiana. Ap\u00f3s ser obrigado a apresentar um v\u00eddeo em que Lula cita apenas tangencialmente a candidatura dele, em entrevista \u00e0 r\u00e1dio Sociedade FM, Geraldo conseguiu gravar com o presidente em meio a um turbilh\u00e3o de outros candidatos que estiveram com ele em Bras\u00edlia. Foi mais um na multid\u00e3o, mas pelo menos garantiu alguns segundos com Lula para a propaganda eleitoral.<\/p>\n<p>Entretanto, a bengala \u201cLula\u201d n\u00e3o \u00e9 exclusividade de Geraldo Jr. J\u00e1 foi usada em 2022 pelo pr\u00f3prio Jer\u00f4nimo e, at\u00e9 o m\u00eas de outubro, estar\u00e1 presente em diversas campanhas pela Bahia. Z\u00e9 Neto, em Feira de Santana, Waldenor Cardoso, em Vit\u00f3ria da Conquista, e Luiz Caetano, em Cama\u00e7ari, para ficar restrito apenas aos munic\u00edpios com a possibilidade de segundo turno, repetem diuturnamente que est\u00e3o do lado de Lula. Chega a ser ir\u00f4nico que o molusco tenha diversos tent\u00e1culos, j\u00e1 que s\u00f3 assim o presidente conseguiria dar conta de tantas promessas que fazem em nome dele.<\/p>\n<p>H\u00e1 at\u00e9 briga judicial para que candidatos de partidos aliados, como PSD e Avante, possam colocar fotos de Lula, de Jer\u00f4nimo, de Rui Costa e de Jaques Wagner em publica\u00e7\u00f5es nas redes sociais, ainda que n\u00e3o figurem como filiados ao Partidos dos Trabalhadores. Se entre 2016 e 2018, o petismo quase ficou classificado como uma doen\u00e7a infectocontagiosa, que afastava pol\u00edticos, em 2024 a onda parece ter virado completamente, ao ponto de Lula ser figura carimbada em 100% das campanhas eleitorais de aliados ou simpatizantes.<\/p>\n<p>Enquanto estrat\u00e9gica pol\u00edtica, a compreens\u00e3o \u00e9 at\u00e9 f\u00e1cil. Foi assim at\u00e9 com Jair Bolsonaro em 2020 e at\u00e9 2022 (ainda que em uma escala muito menor e menos impactante), j\u00e1 que a ideia \u00e9 tentar surfar na popularidade do l\u00edder do projeto pol\u00edtico em quest\u00e3o. Por\u00e9m \u00e9 extremamente limitante quando olhamos sob a perspectiva de que h\u00e1 uma demanda social por renova\u00e7\u00e3o e por um \u201cnovo\u201d vi\u00e9s para a pol\u00edtica. Ao incorrer nesse erro, houve a trag\u00e9dia eleitoral de 2018, por exemplo. E, convenhamos, dificilmente o pr\u00f3prio Lula quereria ver uma reprise do filme de terror vivenciado na democracia brasileira at\u00e9 o 8 de janeiro de 2023&#8230;<\/p>\n<p>Lula aparece como bengala, mas n\u00e3o deveria. Agora, o problema est\u00e1 nos pol\u00edticos que o usam dessa forma ou no eleitor que ainda se impacta com esse discurso restritivo? (Bahia Noticias)<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"post-outer\">\n<div class=\"post hentry\">\n<h3 class=\"post-title entry-title\"><a href=\"https:\/\/www.verdinhoitabuna.blog.br\/2024\/09\/pm-aposentado-e-suspeito-de-trafico-de.html\">PM aposentado e suspeito de tr\u00e1fico de drogas s\u00e3o presos em Salvador<\/a><\/h3>\n<div class=\"post-header\">\n<div class=\"post-header-line-1\"><\/div>\n<\/div>\n<div id=\"post-body-817089635001848970\" class=\"post-body entry-content\">\n<div class=\"separator\"><a href=\"https:\/\/blogger.googleusercontent.com\/img\/a\/AVvXsEhyOSU_DCf86QiLiaCJ9EBwZBTa8XJ6gzDBLhEsg3Vd_TJe7xi5an5NeaIw3373xn6dXOlNi47Prf04l_ViUNrUQDOFKLqfPf_mHW9Rf1sybjAkPxPaCxCvjJpNA8FM90PxB3xjlzDP-ePeWJIA6MdQtDeUBoc9BMW8qxmH2iyXjQ2mdTBgzjvnWeblrpM\"><img loading=\"lazy\" src=\"https:\/\/blogger.googleusercontent.com\/img\/a\/AVvXsEhyOSU_DCf86QiLiaCJ9EBwZBTa8XJ6gzDBLhEsg3Vd_TJe7xi5an5NeaIw3373xn6dXOlNi47Prf04l_ViUNrUQDOFKLqfPf_mHW9Rf1sybjAkPxPaCxCvjJpNA8FM90PxB3xjlzDP-ePeWJIA6MdQtDeUBoc9BMW8qxmH2iyXjQ2mdTBgzjvnWeblrpM=w508-h371\" alt=\"\" width=\"508\" height=\"371\" data-original-height=\"398\" data-original-width=\"544\" \/><\/a><\/div>\n<p>&nbsp;<\/p>\n<p>Um policial militar aposentado e outro homem, de 24 anos, foram presos em flagrante suspeitos de tr\u00e1fico de drogas, em Salvador. O caso ocorreu na noite de sexta-feira (6), no bairro do Uruguai.<\/p>\n<p>Em nota, a Pol\u00edcia Militar (PM) informou que a dupla estava em um carro de luxo quando foi abordada por agentes. O suspeito estava armado e admitiu que estava no local para negociar uma grande quantidade de entorpecentes, enquanto o soldado da reserva, tamb\u00e9m armado, fazia a seguran\u00e7a dele.<\/p>\n<p>Os dois foram encaminhados para Departamento de Especializado de Investiga\u00e7\u00e3o e Repress\u00e3o ao Narcotr\u00e1fico (Denarc), no bairro da Pituba. Eles n\u00e3o tiveram nomes divulgados.<\/p>\n<p>Durante a a\u00e7\u00e3o, foram apreendidos, al\u00e9m de por\u00e7\u00f5es de droga, um ve\u00edculo Mercedes C180, um rev\u00f3lver e uma pistola norte-americana de uso proibido no Brasil, com seus respectivos carregadores e muni\u00e7\u00f5es, tr\u00eas rel\u00f3gios importados e dois celulares Iphone 15.<\/p>\n<\/div>\n<div class=\"post-footer\">\n<div class=\"post-footer-line post-footer-line-1\">\n<div class=\"post-share-buttons goog-inline-block\"><\/div>\n<\/div>\n<div class=\"post-footer-line post-footer-line-2\"><\/div>\n<div class=\"post-footer-line post-footer-line-3\"><a href=\"https:\/\/www.verdinhoitabuna.blog.br\/2024\/09\/carro-de-candidata-prefeitura-de-cidade.html\">Carro de candidata \u00e0 prefeitura de cidade baiana \u00e9 alvo de disparos de arma de fogo em Itapitanga<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"post-outer\">\n<div class=\"post hentry\">\n<div id=\"post-body-5044475070681414540\" class=\"post-body entry-content\">\n<div class=\"separator\"><a href=\"https:\/\/blogger.googleusercontent.com\/img\/a\/AVvXsEiwuFQSorYKACmUV3lLSFYQYUnxQSMpXNfQHub8H-NVtD57qOhGAfVr8gmPsbpx5lJSTJ9S-ySGf-jGuB0LhYfRsVz3AWOgBSWU7IGKnVj9jTN6kpcESZ-d-X544cUH3a0owdvDaEKEmZu1yEMiunglZwDixrg1lSCFwJLnFIfxhJ_pYQyMVYlers00OPI\"><img loading=\"lazy\" src=\"https:\/\/blogger.googleusercontent.com\/img\/a\/AVvXsEiwuFQSorYKACmUV3lLSFYQYUnxQSMpXNfQHub8H-NVtD57qOhGAfVr8gmPsbpx5lJSTJ9S-ySGf-jGuB0LhYfRsVz3AWOgBSWU7IGKnVj9jTN6kpcESZ-d-X544cUH3a0owdvDaEKEmZu1yEMiunglZwDixrg1lSCFwJLnFIfxhJ_pYQyMVYlers00OPI=w566-h333\" alt=\"\" width=\"566\" height=\"333\" data-original-height=\"587\" data-original-width=\"1000\" \/><\/a><\/div>\n<p>&nbsp;<\/p>\n<p>Uma candidata \u00e0 prefeitura de Itapitanga, no sul da Bahia, teve o carro atingido por disparos de arma de fogo durante uma viagem, na BR-030. O caso \u00e9 investigado pela Pol\u00edcia Civil (PC) e at\u00e9 este s\u00e1bado (7), nenhum suspeito foi preso. As informa\u00e7\u00f5es s\u00e3o da Pol\u00edcia Militar.<\/p>\n<p>O crime ocorreu na noite de quinta-feira (5) e foi registrado em delegacia na tarde de sexta (6), de acordo com a PC. Joanice Alves da Silva, de 55 anos, retornava de Jequi\u00e9, no sudoeste, onde participou de um evento de campanha.<\/p>\n<p>Quando passava pelo trevo do munic\u00edpio de Gongogi, dois homens em uma motocicleta, que ainda n\u00e3o foram identificados, atiraram v\u00e1rias vezes contra o autom\u00f3vel. Os tiros danificaram o para-brisa frontal e o vidro lateral direito.<\/p>\n<p>O ve\u00edculo era conduzido pelo companheiro de Joanice, Felipe Jos\u00e9 Alves da Silva Ara\u00fajo. Ele acelerou e conseguiu pedir ajuda ao funcion\u00e1rio de uma fazenda e chamou a Pol\u00edcia Militar. Apesar do susto, eles n\u00e3o tiveram ferimentos.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; O Governo do Estado abriu um processo seletivo para contrata\u00e7\u00e3o de 1.624 profissionais da educa\u00e7\u00e3o em diversas cidades da Bahia. As oportunidades foram divulgadas no Di\u00e1rio Oficial de sexta-feira (7) e as inscri\u00e7\u00f5es poder\u00e3o ser feitas a partir de 12 de setembro. As inscri\u00e7\u00f5es dever\u00e3o ser feitas pela internet, at\u00e9 2 de outubro. As [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":12301,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[9],"tags":[],"_links":{"self":[{"href":"https:\/\/www.correiodascidades.com.br\/v1\/wp-json\/wp\/v2\/posts\/12303"}],"collection":[{"href":"https:\/\/www.correiodascidades.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.correiodascidades.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.correiodascidades.com.br\/v1\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.correiodascidades.com.br\/v1\/wp-json\/wp\/v2\/comments?post=12303"}],"version-history":[{"count":2,"href":"https:\/\/www.correiodascidades.com.br\/v1\/wp-json\/wp\/v2\/posts\/12303\/revisions"}],"predecessor-version":[{"id":12305,"href":"https:\/\/www.correiodascidades.com.br\/v1\/wp-json\/wp\/v2\/posts\/12303\/revisions\/12305"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.correiodascidades.com.br\/v1\/wp-json\/wp\/v2\/media\/12301"}],"wp:attachment":[{"href":"https:\/\/www.correiodascidades.com.br\/v1\/wp-json\/wp\/v2\/media?parent=12303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.correiodascidades.com.br\/v1\/wp-json\/wp\/v2\/categories?post=12303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.correiodascidades.com.br\/v1\/wp-json\/wp\/v2\/tags?post=12303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}