{"id":21920,"date":"2026-05-13T09:10:58","date_gmt":"2026-05-13T12:10:58","guid":{"rendered":"https:\/\/www.correiodascidades.com.br\/v1\/?p=21920"},"modified":"2026-05-13T09:10:58","modified_gmt":"2026-05-13T12:10:58","slug":"maternidade-municipal-de-salvador-acolhe-gestante-do-extremo-sul-da-bahia-e-celebra-nascimento-raro-de-trigemeos-redacao-por-redacao-12-05-2026-em-cotidiano-tempo-de-leitura-2-min","status":"publish","type":"post","link":"https:\/\/www.correiodascidades.com.br\/v1\/2026\/05\/13\/maternidade-municipal-de-salvador-acolhe-gestante-do-extremo-sul-da-bahia-e-celebra-nascimento-raro-de-trigemeos-redacao-por-redacao-12-05-2026-em-cotidiano-tempo-de-leitura-2-min\/","title":{"rendered":"Maternidade municipal de Salvador acolhe gestante do Extremo Sul da Bahia e celebra nascimento raro de trig\u00eameos Reda\u00e7\u00e3o por Reda\u00e7\u00e3o  12\/05\/2026 em Cotidiano Tempo de leitura: 2 min"},"content":{"rendered":"<p><img src=\"https:\/\/www.correiodascidades.com.br\/v1\/wp-content\/uploads\/2026\/05\/trigemeos.maternidademunici-768x477-1.jpg\" \/><\/p>\n<p><span class=\"dropcap \">U<\/span>m nascimento raro e cercado de emo\u00e7\u00e3o marcou a noite da \u00faltima segunda-feira (11) na Maternidade e Hospital da Crian\u00e7a (MHC) Deputado Alan Sanches, em Salvador. A paciente Michelle Zerbinati Medeiros, residente em Itamaraju, no Extremo Sul da Bahia, deu \u00e0 luz trig\u00eameos ap\u00f3s ser transferida em car\u00e1ter de urg\u00eancia para a capital baiana por meio da regula\u00e7\u00e3o do SUS. <!--more--><\/p>\n<p>Michelle foi inicialmente atendida em Itamaraju e, posteriormente, transferida para Teixeira de Freitas. Diante da complexidade do caso \u2014 uma gesta\u00e7\u00e3o trigemelar de alto risco \u2014, a paciente, admitida com 35 semanas de gesta\u00e7\u00e3o, foi encaminhada como vaga zero para Salvador, sendo acolhida pela equipe especializada da maternidade municipal.<\/p>\n<p>Na unidade, nasceram os trig\u00eameos Felipe, com 2.322g, Lia, com 2.156g, e Liz, com 2.112g. O nascimento dos tr\u00eas beb\u00eas mobilizou equipes multiprofissionais e foi celebrado como um momento de grande emo\u00e7\u00e3o para familiares e profissionais envolvidos na assist\u00eancia.<\/p>\n<p>Al\u00e9m da emo\u00e7\u00e3o que envolve a chegada dos beb\u00eas, o caso chama a aten\u00e7\u00e3o pela raridade. A gesta\u00e7\u00e3o de trig\u00eameos \u00e9 incomum e exige acompanhamento intensivo, al\u00e9m de uma estrutura hospitalar preparada para atender m\u00e3es e rec\u00e9m-nascidos com seguran\u00e7a, especialmente diante do risco aumentado de prematuridade e outras intercorr\u00eancias neonatais.<\/p>\n<p>O caso refor\u00e7a a import\u00e2ncia de uma estrutura materno-infantil especializada para absorver demandas complexas, evidenciando o papel estrat\u00e9gico da Maternidade Hospital da Crian\u00e7a Deputado Alan Sanches.<\/p>\n<p>Primeira maternidade da rede municipal de Salvador, a unidade de m\u00e9dia e alta complexidade conta com 198 leitos, centro obst\u00e9trico e cir\u00fargico, UTIs adulto, neonatal e pedi\u00e1trica, emerg\u00eancia obst\u00e9trica e pedi\u00e1trica, garantindo assist\u00eancia integral desde a gesta\u00e7\u00e3o at\u00e9 os cuidados neonatais especializados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um nascimento raro e cercado de emo\u00e7\u00e3o marcou a noite da \u00faltima segunda-feira (11) na Maternidade e Hospital da Crian\u00e7a (MHC) Deputado Alan Sanches, em Salvador. A paciente Michelle Zerbinati Medeiros, residente em Itamaraju, no Extremo Sul da Bahia, deu \u00e0 luz trig\u00eameos ap\u00f3s ser transferida em car\u00e1ter de urg\u00eancia para a capital baiana por [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":21921,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.correiodascidades.com.br\/v1\/wp-json\/wp\/v2\/posts\/21920"}],"collection":[{"href":"https:\/\/www.correiodascidades.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.correiodascidades.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.correiodascidades.com.br\/v1\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.correiodascidades.com.br\/v1\/wp-json\/wp\/v2\/comments?post=21920"}],"version-history":[{"count":1,"href":"https:\/\/www.correiodascidades.com.br\/v1\/wp-json\/wp\/v2\/posts\/21920\/revisions"}],"predecessor-version":[{"id":21922,"href":"https:\/\/www.correiodascidades.com.br\/v1\/wp-json\/wp\/v2\/posts\/21920\/revisions\/21922"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.correiodascidades.com.br\/v1\/wp-json\/wp\/v2\/media\/21921"}],"wp:attachment":[{"href":"https:\/\/www.correiodascidades.com.br\/v1\/wp-json\/wp\/v2\/media?parent=21920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.correiodascidades.com.br\/v1\/wp-json\/wp\/v2\/categories?post=21920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.correiodascidades.com.br\/v1\/wp-json\/wp\/v2\/tags?post=21920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}